{"id":44993,"date":"2025-12-09T12:27:15","date_gmt":"2025-12-09T15:27:15","guid":{"rendered":"https:\/\/radio94fm.net\/site\/?p=44993"},"modified":"2025-12-09T12:35:01","modified_gmt":"2025-12-09T15:35:01","slug":"fagamon-inaugura-nova-clinica-de-psicologia","status":"publish","type":"post","link":"https:\/\/radio94fm.net\/site\/fagamon-inaugura-nova-clinica-de-psicologia\/","title":{"rendered":"FAGAMON INAUGURA NOVA CL\u00cdNICA DE PSICOLOGIA"},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-69160131-6388-832e-ab70-a44f473478b1-4\" data-testid=\"conversation-turn-8\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"a649dbdc-f451-4798-af65-102afa273a5f\" data-message-model-slug=\"gpt-5-1\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<p data-start=\"418\" data-end=\"754\">A Fagamon inaugurou sua nova cl\u00ednica de psicologia, um espa\u00e7o que fortalece tanto a forma\u00e7\u00e3o pr\u00e1tica dos estudantes quanto o atendimento psicol\u00f3gico oferecido \u00e0 popula\u00e7\u00e3o de Lavras. A iniciativa marca um avan\u00e7o importante para a institui\u00e7\u00e3o, ampliando o acesso da comunidade a servi\u00e7os especializados e de qualidade.<\/p>\n<p data-start=\"756\" data-end=\"1217\">A coordenadora do curso de Psicologia, <strong data-start=\"795\" data-end=\"816\">Maria Camila Lima<\/strong>, explica que o novo espa\u00e7o representa uma mudan\u00e7a significativa na rotina acad\u00eamica. \u201cA cl\u00ednica revoluciona a pr\u00e1tica dos estudantes ao oferecer um ambiente real e supervisionado para o desenvolvimento de compet\u00eancias. Ao mesmo tempo, expande o impacto social ao levar servi\u00e7os psicol\u00f3gicos acess\u00edveis \u00e0 comunidade de Lavras. \u00c9 a uni\u00e3o entre excel\u00eancia acad\u00eamica e responsabilidade social\u201d, afirma.<\/p>\n<p data-start=\"1219\" data-end=\"1598\">Segundo a coordenadora, o servi\u00e7o se diferencia pela abordagem multimodal, que inclui atendimentos individuais, grupos terap\u00eauticos e a\u00e7\u00f5es de psicoeduca\u00e7\u00e3o. \u201cContamos com instala\u00e7\u00f5es modernas, tecnologia de ponta e um corpo docente especializado que supervisiona diretamente cada atendimento. Isso garante uma pr\u00e1tica atualizada e baseada em evid\u00eancias\u201d, destaca Maria Camila.<\/p>\n<p data-start=\"1600\" data-end=\"2052\">Para acessar os atendimentos, basta realizar o cadastro no site da Fagamon, na aba Cl\u00ednica de Psicologia. Ap\u00f3s o registro, a equipe entra em contato para orientar e agendar a primeira consulta. Nos pr\u00f3ximos meses, a cl\u00ednica deve implementar novos projetos, oficinas e a\u00e7\u00f5es comunit\u00e1rias, aproximando ainda mais a institui\u00e7\u00e3o da popula\u00e7\u00e3o lavrense. A iniciativa consolida a cl\u00ednica como um importante instrumento de desenvolvimento acad\u00eamico e social.<\/p>\n<p data-start=\"2054\" data-end=\"2245\" data-is-last-node=\"\" data-is-only-node=\"\">\ud83d\udcac Quer saber mais sobre os servi\u00e7os da nova Cl\u00ednica de Psicologia da Fagamon? Ou\u00e7a o <em data-start=\"2140\" data-end=\"2158\">Fique Por Dentro<\/em> na 94FM e fique sempre bem informado sobre o que acontece em Lavras e no Sul de Minas!<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-44993-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/12\/FPD-CLINICA-PSICOLOGIA-FAGAMMON-08-12-25.mp3?_=1\" \/><a href=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/12\/FPD-CLINICA-PSICOLOGIA-FAGAMMON-08-12-25.mp3\">https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/12\/FPD-CLINICA-PSICOLOGIA-FAGAMMON-08-12-25.mp3<\/a><\/audio>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>A Fagamon inaugurou sua nova cl\u00ednica de psicologia, um espa\u00e7o que fortalece tanto a forma\u00e7\u00e3o pr\u00e1tica dos estudantes quanto o atendimento psicol\u00f3gico oferecido \u00e0 popula\u00e7\u00e3o de Lavras. A iniciativa marca um avan\u00e7o importante para a institui\u00e7\u00e3o, ampliando o acesso da comunidade a servi\u00e7os especializados e de qualidade. A coordenadora do curso de Psicologia, Maria Camila&#8230;<\/p>\n","protected":false},"author":3,"featured_media":44985,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-44993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fique-por-dentro","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/comments?post=44993"}],"version-history":[{"count":2,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44993\/revisions"}],"predecessor-version":[{"id":44995,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44993\/revisions\/44995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media\/44985"}],"wp:attachment":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media?parent=44993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/categories?post=44993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/tags?post=44993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}