{"id":44927,"date":"2025-11-28T16:20:48","date_gmt":"2025-11-28T19:20:48","guid":{"rendered":"https:\/\/radio94fm.net\/site\/?p=44927"},"modified":"2025-11-28T16:20:48","modified_gmt":"2025-11-28T19:20:48","slug":"pmmg-celebra-250-anos-com-documentario-2","status":"publish","type":"post","link":"https:\/\/radio94fm.net\/site\/pmmg-celebra-250-anos-com-documentario-2\/","title":{"rendered":"PMMG CELEBRA 250 ANOS COM DOCUMENT\u00c1RIO &#8211; 2"},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-69160131-6388-832e-ab70-a44f473478b1-1\" data-testid=\"conversation-turn-30\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"22fdf612-6f29-48bc-85da-9abe64dc7bf5\" data-message-model-slug=\"gpt-5-1\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<p data-start=\"460\" data-end=\"839\">Foi lan\u00e7ado no audit\u00f3rio da FADMinas, em Tirapu\u00e3, o document\u00e1rio institucional <em data-start=\"539\" data-end=\"583\">A Transforma\u00e7\u00e3o de uma Pol\u00edcia que Protege<\/em>, em comemora\u00e7\u00e3o aos 250 anos da Pol\u00edcia Militar de Minas Gerais. O evento reuniu autoridades, convidados e moradores da regi\u00e3o. A equipe da 94FM acompanhou o lan\u00e7amento e registrou depoimentos sobre a evolu\u00e7\u00e3o e o papel da corpora\u00e7\u00e3o na sociedade mineira.<\/p>\n<p data-start=\"841\" data-end=\"1300\">O <strong>tenente-coronel Alexandre Milhomes Silva<\/strong>, comandante do 8\u00ba Batalh\u00e3o, destacou que a PMMG passou por profundas transforma\u00e7\u00f5es estruturais e tecnol\u00f3gicas ao longo dos anos. Ele ressaltou que a pol\u00edcia, antes voltada para o combate a conflitos nas minas e ao com\u00e9rcio ilegal, tornou-se uma institui\u00e7\u00e3o essencialmente comunit\u00e1ria. Segundo o comandante, a parceria com a popula\u00e7\u00e3o e com outros \u00f3rg\u00e3os p\u00fablicos \u00e9 indispens\u00e1vel para fortalecer a seguran\u00e7a p\u00fablica.<\/p>\n<p data-start=\"1302\" data-end=\"1731\">Com 39 anos de carreira, o <strong>subtenente Nelson<\/strong> afirmou que viver a evolu\u00e7\u00e3o da institui\u00e7\u00e3o foi motivo de orgulho. Ele destacou avan\u00e7os na moderniza\u00e7\u00e3o da corpora\u00e7\u00e3o, bem como a import\u00e2ncia de valorizar o p\u00fablico interno para assegurar um servi\u00e7o eficiente \u00e0 sociedade. J\u00e1 o vereador <strong>Gil<\/strong> do Tirapu\u00e3 elogiou o evento e refor\u00e7ou a relev\u00e2ncia da PMMG, que, segundo ele, tem realizado um trabalho marcante em todas as regi\u00f5es da cidade.<\/p>\n<p data-start=\"1733\" data-end=\"2057\">O document\u00e1rio celebra a hist\u00f3ria, o compromisso e a dedica\u00e7\u00e3o da corpora\u00e7\u00e3o ao longo de dois s\u00e9culos e meio. A 94FM refor\u00e7a que reconhecer essa trajet\u00f3ria \u00e9 valorizar o servi\u00e7o prestado diariamente por homens e mulheres que se dedicam \u00e0 prote\u00e7\u00e3o da popula\u00e7\u00e3o. O conte\u00fado est\u00e1 dispon\u00edvel no canal oficial da PMMG no YouTube.<\/p>\n<p data-start=\"2059\" data-end=\"2270\" data-is-last-node=\"\" data-is-only-node=\"\">\ud83d\udcac Quer saber mais sobre seguran\u00e7a p\u00fablica, cidadania e o trabalho das institui\u00e7\u00f5es em Minas Gerais? Ou\u00e7a o Fique Por Dentro na <strong>94FM<\/strong> e fique sempre bem informado sobre o que acontece em Lavras e no Sul de Minas!<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-44927-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/11\/FPD-DOCUMENTARIO-PMMG-02.mp3?_=1\" \/><a href=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/11\/FPD-DOCUMENTARIO-PMMG-02.mp3\">https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/11\/FPD-DOCUMENTARIO-PMMG-02.mp3<\/a><\/audio>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Foi lan\u00e7ado no audit\u00f3rio da FADMinas, em Tirapu\u00e3, o document\u00e1rio institucional A Transforma\u00e7\u00e3o de uma Pol\u00edcia que Protege, em comemora\u00e7\u00e3o aos 250 anos da Pol\u00edcia Militar de Minas Gerais. O evento reuniu autoridades, convidados e moradores da regi\u00e3o. A equipe da 94FM acompanhou o lan\u00e7amento e registrou depoimentos sobre a evolu\u00e7\u00e3o e o papel da&#8230;<\/p>\n","protected":false},"author":3,"featured_media":44923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-44927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fique-por-dentro","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/comments?post=44927"}],"version-history":[{"count":1,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44927\/revisions"}],"predecessor-version":[{"id":44928,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44927\/revisions\/44928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media\/44923"}],"wp:attachment":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media?parent=44927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/categories?post=44927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/tags?post=44927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}