{"id":44859,"date":"2025-11-21T12:22:47","date_gmt":"2025-11-21T15:22:47","guid":{"rendered":"https:\/\/radio94fm.net\/site\/?p=44859"},"modified":"2025-11-21T12:22:47","modified_gmt":"2025-11-21T15:22:47","slug":"unilavras-realiza-semana-de-oportunidades-e-carreira","status":"publish","type":"post","link":"https:\/\/radio94fm.net\/site\/unilavras-realiza-semana-de-oportunidades-e-carreira\/","title":{"rendered":"UNILAVRAS REALIZA SEMANA DE OPORTUNIDADES E CARREIRA"},"content":{"rendered":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"da120800-732f-4738-9048-e575ba52bab8\" data-testid=\"conversation-turn-22\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"2466f76b-b79e-4ea9-b152-6a2b2de3bc81\" data-message-model-slug=\"gpt-5-1\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<p data-start=\"466\" data-end=\"1082\">O Unilavras promoveu a primeira Semana de Oportunidades e Carreira, com programa\u00e7\u00e3o dedicada a conectar estudantes e mercado de trabalho. O evento reuniu palestras, oficinas pr\u00e1ticas e, no encerramento, a Feira de Oportunidades e Carreira, que contou com empresas de Lavras e regi\u00e3o apresentando vagas, programas de est\u00e1gio e possibilidades de desenvolvimento profissional. Segundo o pr\u00f3-reitor de Desenvolvimento, <strong>Luiz Felipe Argenta<\/strong>, as empresas foram convidadas como parceiras para divulgar suas marcas empregadoras e se aproximar dos talentos formados pela institui\u00e7\u00e3o, totalizando 20 participantes nesta edi\u00e7\u00e3o.<\/p>\n<p data-start=\"1084\" data-end=\"1592\">O pr\u00f3-reitor explica que a semana contribuiu diretamente para a prepara\u00e7\u00e3o dos estudantes, oferecendo contato com especialistas, debates sobre tend\u00eancias do mercado e oficinas voltadas ao desenvolvimento de compet\u00eancias. Entre as atividades, destaque para a oficina de entrevista simulada, que ajuda os estudantes a transformar conhecimentos dos cursos em habilidades valorizadas pelas empresas. Para Argenta, essa pr\u00e1tica aumenta a confian\u00e7a dos jovens e melhora o desempenho no momento decisivo da sele\u00e7\u00e3o.<\/p>\n<p data-start=\"1594\" data-end=\"2080\">Al\u00e9m das oficinas, os alunos puderam interagir com recrutadores durante a feira, ampliando a compreens\u00e3o sobre habilidades exigidas, processos seletivos e oportunidades reais em empresas da regi\u00e3o. Essa aproxima\u00e7\u00e3o fortalece a empregabilidade dos estudantes e demonstra o compromisso do Unilavras em criar pontes entre forma\u00e7\u00e3o acad\u00eamica e atua\u00e7\u00e3o profissional. Com iniciativas como essa, a institui\u00e7\u00e3o refor\u00e7a seu papel no desenvolvimento de carreiras e na conex\u00e3o com o mercado local.<\/p>\n<p data-start=\"2082\" data-end=\"2269\" data-is-last-node=\"\" data-is-only-node=\"\">\ud83d\udcac Quer saber mais sobre educa\u00e7\u00e3o e qualifica\u00e7\u00e3o? Ou\u00e7a o Fique Por Dentro na 94FM e fique sempre bem informado sobre o que acontece em Lavras e no Sul de Minas!<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-44859-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/11\/FPD-SEMANA-DE-OPORTUNIDADES-21-11-25.mp3?_=1\" \/><a href=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/11\/FPD-SEMANA-DE-OPORTUNIDADES-21-11-25.mp3\">https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2025\/11\/FPD-SEMANA-DE-OPORTUNIDADES-21-11-25.mp3<\/a><\/audio>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>O Unilavras promoveu a primeira Semana de Oportunidades e Carreira, com programa\u00e7\u00e3o dedicada a conectar estudantes e mercado de trabalho. O evento reuniu palestras, oficinas pr\u00e1ticas e, no encerramento, a Feira de Oportunidades e Carreira, que contou com empresas de Lavras e regi\u00e3o apresentando vagas, programas de est\u00e1gio e possibilidades de desenvolvimento profissional. Segundo o&#8230;<\/p>\n","protected":false},"author":3,"featured_media":44860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-44859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fique-por-dentro","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/comments?post=44859"}],"version-history":[{"count":1,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44859\/revisions"}],"predecessor-version":[{"id":44865,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/44859\/revisions\/44865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media\/44860"}],"wp:attachment":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media?parent=44859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/categories?post=44859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/tags?post=44859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}