{"id":39224,"date":"2023-02-24T18:44:41","date_gmt":"2023-02-24T18:44:41","guid":{"rendered":"https:\/\/radio94fm.net\/site\/?p=39224"},"modified":"2023-02-24T18:44:41","modified_gmt":"2023-02-24T18:44:41","slug":"pesquisas-apontam-que-o-clima-influencia-humor-das-pessoas","status":"publish","type":"post","link":"https:\/\/radio94fm.net\/site\/pesquisas-apontam-que-o-clima-influencia-humor-das-pessoas\/","title":{"rendered":"PESQUISAS APONTAM QUE O CLIMA INFLU\u00caNCIA HUMOR DAS PESSOAS."},"content":{"rendered":"<p>No in\u00edcio de ano muitas pessoas reclamam e pedem para o aguaceiro passar mas, quando o sol brilha e do c\u00e9u n\u00e3o cai gota alguma, as pessoas novamente come\u00e7am a reclamar.<\/p>\n<p>A equipe do fique por dentro 94 procurou saber se as pessoas preferem: o per\u00edodo de chuva ou o sol com calorz\u00e3o.<\/p>\n<p>Artigos de especialistas em psicologia ambiental mostram que&nbsp;&nbsp; a vida e a abund\u00e2ncia no planeta dependem da varia\u00e7\u00e3o clim\u00e1tica j\u00e1 artigo da ci\u00eancia do sentir, aponta: \u201cse o clima estiver interferindo em seu humor procure sentir&nbsp;&nbsp; gratid\u00e3o pela chuva e pelo sol, \u00e9 tudo uma quest\u00e3o de equil\u00edbrio\u201d<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-39224-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2023\/02\/FPD-CLIMA-INFLUENCIA-HUMOR-23-02-23.mp3?_=1\" \/><a href=\"https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2023\/02\/FPD-CLIMA-INFLUENCIA-HUMOR-23-02-23.mp3\">https:\/\/radio94fm.net\/site\/wp-content\/uploads\/2023\/02\/FPD-CLIMA-INFLUENCIA-HUMOR-23-02-23.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio de ano muitas pessoas reclamam e pedem para o aguaceiro passar mas, quando o sol brilha e do c\u00e9u n\u00e3o cai gota alguma, as pessoas novamente come\u00e7am a reclamar. A equipe do fique por dentro 94 procurou saber se as pessoas preferem: o per\u00edodo de chuva ou o sol com calorz\u00e3o. Artigos de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":39226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-39224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fique-por-dentro","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/39224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/comments?post=39224"}],"version-history":[{"count":1,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/39224\/revisions"}],"predecessor-version":[{"id":39227,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/39224\/revisions\/39227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media\/39226"}],"wp:attachment":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media?parent=39224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/categories?post=39224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/tags?post=39224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}