{"id":37478,"date":"2022-06-10T08:53:16","date_gmt":"2022-06-10T11:53:16","guid":{"rendered":"http:\/\/www.radio94fm.net\/site\/?p=37478"},"modified":"2022-06-10T08:53:16","modified_gmt":"2022-06-10T11:53:16","slug":"fique-por-dentro-dia-internacional-de-combate-a-gordura-no-figado-alerta-para-problema-que-atinge-34-da-populacao-mundial","status":"publish","type":"post","link":"https:\/\/radio94fm.net\/site\/fique-por-dentro-dia-internacional-de-combate-a-gordura-no-figado-alerta-para-problema-que-atinge-34-da-populacao-mundial\/","title":{"rendered":"FIQUE POR DENTRO: DIA INTERNACIONAL DE COMBATE \u00c0 GORDURA NO F\u00cdGADO ALERTA PARA PROBLEMA QUE ATINGE 34% DA POPULA\u00c7\u00c3O MUNDIAL"},"content":{"rendered":"<p><a href=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/02\/FIQUE-POR-DENTRO-2-BANNER.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32065 aligncenter\" src=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/02\/FIQUE-POR-DENTRO-2-BANNER.gif\" alt=\"\" width=\"604\" height=\"154\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\"><a href=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2022\/06\/download-79.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-37480\" src=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2022\/06\/download-79.jpg\" alt=\"\" width=\"304\" height=\"159\"><\/a>No dia 12 de junho, centenas de organiza\u00e7\u00f5es voltadas para a sa\u00fade pelo mundo se unem para ampliar a discuss\u00e3o sobre o crescimento dos casos de esteatose hep\u00e1tica n\u00e3o alco\u00f3lica. A doen\u00e7a que afeta aproximadamente 34% da popula\u00e7\u00e3o adulta \u00e9 caracterizada pelo ac\u00famulo excessivo de gordura nas c\u00e9lulas do f\u00edgado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A hepatologista, Liliana Sampaio alerta que as doen\u00e7as no f\u00edgado n\u00e3o costumam dar sinais e quando eles aparecem, geralmente, o quadro j\u00e1 est\u00e1 grave.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Apesar de n\u00e3o existir um tratamento espec\u00edfico, m\u00e9dicos recomendam que para diminuir a gordura no f\u00edgado deve-se melhorar a qualidade de vida, incluir atividades f\u00edsicas no dia a dia e garantir uma alimenta\u00e7\u00e3o de qualidade.<\/span><\/p>\n<p>Ou\u00e7a!<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-37478-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2022\/06\/FPD-DIA-DE-COMBATE-A-GORDURA-NO-FIGADO-10-06-22-1.mp3?_=1\" \/><a href=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2022\/06\/FPD-DIA-DE-COMBATE-A-GORDURA-NO-FIGADO-10-06-22-1.mp3\">http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2022\/06\/FPD-DIA-DE-COMBATE-A-GORDURA-NO-FIGADO-10-06-22-1.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/02\/FIQUE-POR-DENTRO-1.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-32063 aligncenter\" src=\"http:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/02\/FIQUE-POR-DENTRO-1.gif\" alt=\"\" width=\"604\" height=\"80\"><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; No dia 12 de junho, centenas de organiza\u00e7\u00f5es voltadas para a sa\u00fade pelo mundo se unem para ampliar a discuss\u00e3o sobre o crescimento dos casos de esteatose hep\u00e1tica n\u00e3o alco\u00f3lica. A doen\u00e7a que afeta aproximadamente 34% da popula\u00e7\u00e3o adulta \u00e9 caracterizada pelo ac\u00famulo excessivo de gordura nas c\u00e9lulas do f\u00edgado. A hepatologista, Liliana&#8230;<\/p>\n","protected":false},"author":1,"featured_media":37481,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-37478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fique-por-dentro","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/37478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/comments?post=37478"}],"version-history":[{"count":0,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/37478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media\/37481"}],"wp:attachment":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media?parent=37478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/categories?post=37478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/tags?post=37478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}