{"id":32265,"date":"2020-07-28T19:13:19","date_gmt":"2020-07-28T22:13:19","guid":{"rendered":"http:\/\/www.radio94fm.net\/site\/?p=32265"},"modified":"2020-07-28T19:13:19","modified_gmt":"2020-07-28T22:13:19","slug":"delegada-alerta-para-perfis-na-internet-que-assustam-e-induzem-criancas-ao-perigo","status":"publish","type":"post","link":"https:\/\/radio94fm.net\/site\/delegada-alerta-para-perfis-na-internet-que-assustam-e-induzem-criancas-ao-perigo\/","title":{"rendered":"Delegada alerta para perfis na internet que assustam e induzem crian\u00e7as ao perigo"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/02\/FIQUE-POR-DENTRO-1.gif\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">N\u00e3o \u00e9 dif\u00edcil se deparar com perfis nas redes sociais que prop\u00f5e desafios perigosos para crian\u00e7as e adolescentes. Um exemplo desses perfis, \u00e9 o do \u2018homem-pateta\u2019 que tem causado preocupa\u00e7\u00e3o aos pais, especialmente em um per\u00edodo de isolamento social quando os filhos passam mais tempo conectados \u00e0 internet e est\u00e3o mais suscet\u00edveis \u00e0s amea\u00e7as virtuais. Clique e confira a not\u00edcia:<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-32265-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/07\/FPD-DELEGADA-ALERTA-PERFIS-NA-INTERNET-23-07-20-Adelina.mp3?_=1\" \/><a href=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/07\/FPD-DELEGADA-ALERTA-PERFIS-NA-INTERNET-23-07-20-Adelina.mp3\">https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/07\/FPD-DELEGADA-ALERTA-PERFIS-NA-INTERNET-23-07-20-Adelina.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2020\/02\/FIQUE-POR-DENTRO-2-BANNER.gif\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; N\u00e3o \u00e9 dif\u00edcil se deparar com perfis nas redes sociais que prop\u00f5e desafios perigosos para crian\u00e7as e adolescentes. Um exemplo desses perfis, \u00e9 o do \u2018homem-pateta\u2019 que tem causado preocupa\u00e7\u00e3o aos pais, especialmente em um per\u00edodo de isolamento social quando os filhos passam mais tempo conectados \u00e0 internet e est\u00e3o mais suscet\u00edveis&#8230;<\/p>\n","protected":false},"author":1,"featured_media":32267,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-32265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fique-por-dentro","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/32265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/comments?post=32265"}],"version-history":[{"count":0,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/32265\/revisions"}],"wp:attachment":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media?parent=32265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/categories?post=32265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/tags?post=32265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}