{"id":31019,"date":"2019-08-21T16:35:31","date_gmt":"2019-08-21T19:35:31","guid":{"rendered":"http:\/\/www.radio94fm.net\/site\/?p=31019"},"modified":"2019-08-21T16:35:31","modified_gmt":"2019-08-21T19:35:31","slug":"jovens-gammonenses-falam-como-e-estudar-na-escola-mais-tradicional-de-lavras","status":"publish","type":"post","link":"https:\/\/radio94fm.net\/site\/jovens-gammonenses-falam-como-e-estudar-na-escola-mais-tradicional-de-lavras\/","title":{"rendered":"Jovens Gammonenses falam como \u00e9 estudar na escola mais tradicional de Lavras"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2016\/12\/FIQUE-POR-DENTRO-BANNER-DENTRO-2.gif\"><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">O Instituto Presbiteriano Gammon est\u00e1 comemorando em 2019 seu anivers\u00e1rio de 150 anos de exist\u00eancia. S\u00e3o 1 s\u00e9culo e meio participando do desenvolvimento de Lavras e da forma\u00e7\u00e3o de seus habitantes. Clique abaixo para ouvir a mat\u00e9ria\u2026<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<audio class=\"wp-audio-shortcode\" id=\"audio-31019-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2019\/08\/FPD-POVO-FALA-ALUNOS-DO-GAMMON-15-08-19-Pedro.mp3?_=1\" \/><a href=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2019\/08\/FPD-POVO-FALA-ALUNOS-DO-GAMMON-15-08-19-Pedro.mp3\">https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2019\/08\/FPD-POVO-FALA-ALUNOS-DO-GAMMON-15-08-19-Pedro.mp3<\/a><\/audio>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"\" src=\"https:\/\/www.radio94fm.net\/site\/wp-content\/uploads\/2017\/05\/FIQUE-POR-DENTRO-HORARIO-6-1.gif\" alt=\"\" width=\"604\" height=\"144\"><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; O Instituto Presbiteriano Gammon est\u00e1 comemorando em 2019 seu anivers\u00e1rio de 150 anos de exist\u00eancia. S\u00e3o 1 s\u00e9culo e meio participando do desenvolvimento de Lavras e da forma\u00e7\u00e3o de seus habitantes. Clique abaixo para ouvir a mat\u00e9ria\u2026 &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":31021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[54],"tags":[],"class_list":["post-31019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fique-por-dentro","have-post-thumb"],"_links":{"self":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/31019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/comments?post=31019"}],"version-history":[{"count":0,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/posts\/31019\/revisions"}],"wp:attachment":[{"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/media?parent=31019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/categories?post=31019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radio94fm.net\/site\/wp-json\/wp\/v2\/tags?post=31019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}